{"id":486,"date":"2013-08-21T07:04:25","date_gmt":"2013-08-21T05:04:25","guid":{"rendered":"http:\/\/blog.patricksauer.net\/?p=486"},"modified":"2014-02-04T18:41:09","modified_gmt":"2014-02-04T16:41:09","slug":"erfahrungen-zum-studiengang-master-of-science-in-security-management-an-der-fh-brandenburg-teil-9-lohnt-sich-das-studium","status":"publish","type":"post","link":"https:\/\/security.sauer.ninja\/de\/studium\/erfahrungen-zum-studiengang-master-of-science-in-security-management-an-der-fh-brandenburg-teil-9-lohnt-sich-das-studium\/","title":{"rendered":"Erfahrungen zum Studiengang Master of Science in Security Management an der FH Brandenburg \u2013 Teil 9: Lohnt sich das Studium?"},"content":{"rendered":"<p>Ob sich das Studium lohnt, h\u00e4ngt nat\u00fcrlich vom individuellen Fall ab. Ich versuche die Fragestellung von der anderen Seite anzugehen. F\u00fcr wen lohnt es sich nicht? F\u00fcr alle, die einen CISSP, CISM, CISA, TISP usw. besitzen und keinen Master als weiteren Abschluss ben\u00f6tigen. Es ist ganz klar, auch ein aufbauendes Studium richtet sich nicht an Professionals. Im Umkehrschluss kann es sich f\u00fcr alle lohnen, die nach einem Diplom oder Bachelor noch einen Master machen m\u00f6chten und eine formale Qualifikation im Bereich Security Management\u00a0 anstreben.<\/p>\n<p>Dennoch muss man klar sagen, dass man im Sicherheitsumfeld Berufserfahrung ben\u00f6tigt. Ein Abschluss kann helfen, muss aber nicht. Ich halte es f\u00fcr unwahrscheinlich, dass ein Absolvent des Studiums Security Management ohne mindestens ein paar Jahre Berufserfahrung in die Position eines CISOs mit Verantwortung kommt. Ausnahmen best\u00e4tigen sicherlich die Regel. Und es gibt immer noch genug Unternehmen in Deutschland, bei denen \u201eStudierte\u201c h\u00f6her angesehen werden als \u201ePraktiker\u201c. F\u00fcr realistischer halte ich eher eine fachliche Mitarbeit in einer gr\u00f6\u00dferen Security-Abteilung. Aber auch f\u00fcr einen tieferen Einstieg in den Bereich IT-Security wie z.B. Penetration Testing kann das Studium sinnvoll sein. Man sollte dann eben seine Semesterarbeiten, die Projektarbeit und die Master-Thesis geschickt w\u00e4hlen.<\/p>\n<p>Ich selbst trug bereits zu meinem Beginn des Studiums die Verantwortung f\u00fcr den Bereich Security &amp; PCI-Compliance bei einem internationalen Internet Payment Service Provider in Frankfurt. Fachlich hat mir das Studium dennoch weitergeholfen und ich w\u00fcrde es nochmal machen. Einzig negativ ist der mit einem Studium verbundene extrem hohe Aufwand. Dagegen ist die Vorbereitung f\u00fcr die CISSP-Pr\u00fcfung ein Witz. Den pers\u00f6nlichen Aufwand sollte man am besten vor der Immatrikulation absch\u00e4tzen. Einen Master gibt es weder ohne gro\u00dfen Aufwand noch umsonst. Wer neben einer Vollzeitstelle einen Master of Science in Security Management anstrebt, kann seiner Freizeit f\u00fcr einige Zeit lebe wohl sagen. Lohnen kann es sich nat\u00fcrlich trotzdem ;-).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ob sich das Studium lohnt, h\u00e4ngt nat\u00fcrlich vom individuellen Fall ab. Ich versuche die Fragestellung von der anderen Seite anzugehen. F\u00fcr wen lohnt es sich nicht? F\u00fcr alle, die einen CISSP, CISM, CISA, TISP usw. besitzen und keinen Master als weiteren Abschluss ben\u00f6tigen. Es ist ganz klar, auch ein aufbauendes Studium richtet sich nicht an &#8230; <span class=\"more\"><a class=\"more-link\" href=\"https:\/\/security.sauer.ninja\/de\/studium\/erfahrungen-zum-studiengang-master-of-science-in-security-management-an-der-fh-brandenburg-teil-9-lohnt-sich-das-studium\/\">[Read more&#8230;]<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[21],"tags":[29,33,36],"class_list":{"0":"entry","1":"post","2":"publish","3":"author-psauer","4":"post-486","6":"format-standard","7":"category-studium","8":"post_tag-erfahrungsbericht","9":"post_tag-fh-brandenburg","10":"post_tag-master"},"_links":{"self":[{"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/posts\/486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/comments?post=486"}],"version-history":[{"count":5,"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/posts\/486\/revisions"}],"predecessor-version":[{"id":491,"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/posts\/486\/revisions\/491"}],"wp:attachment":[{"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/media?parent=486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/categories?post=486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/security.sauer.ninja\/de\/wp-json\/wp\/v2\/tags?post=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}